{"id":8003,"date":"2021-08-02T01:37:14","date_gmt":"2021-08-02T01:37:14","guid":{"rendered":"https:\/\/tplabs.co\/ametok\/?page_id=8003"},"modified":"2024-09-29T09:11:29","modified_gmt":"2024-09-29T09:11:29","slug":"contatti","status":"publish","type":"page","link":"https:\/\/edil-cave.it\/index.php\/contatti\/","title":{"rendered":"Contatti"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8003\" class=\"elementor elementor-8003\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-094a891 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"094a891\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cd2644\" data-id=\"4cd2644\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7e8f627 elementor-widget elementor-widget-spacer\" data-id=\"7e8f627\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 15-04-2024 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container{height:100%;width:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty,.e-con>.elementor-widget-spacer.elementor-widget-empty{position:relative;min-height:22px;min-width:22px}.e-con-inner>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon,.e-con>.elementor-widget-spacer.elementor-widget-empty .elementor-widget-empty-icon{position:absolute;top:0;bottom:0;left:0;right:0;margin:auto;padding:0;width:22px;height:22px}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-410fe8e align-center elementor-invisible elementor-widget elementor-widget-mae-headings\" data-id=\"410fe8e\" data-element_type=\"widget\" data-widget_type=\"mae-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"master-heading sep-top\">\n\t\t\t<div class=\"sep\"><\/div>\t        \t        \t<div class=\"pre-heading\">Ecco come trovarci<\/div>\n\t        \n\t        \n\t        \t        <h2 class=\"main-heading\">I nostri contatti<\/h2>\n\t        \n\t        \n\t        \t    <\/div>\n\t    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-3934e8d e-flex e-con-boxed e-con e-parent\" data-id=\"3934e8d\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-15c9a8c e-con-full e-flex e-con e-child\" data-id=\"15c9a8c\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f2cd7f elementor-widget elementor-widget-google_maps\" data-id=\"6f2cd7f\" data-element_type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.21.0 - 15-04-2024 *\/\n.elementor-widget-google_maps .elementor-widget-container{overflow:hidden}.elementor-widget-google_maps .elementor-custom-embed{line-height:0}.elementor-widget-google_maps iframe{height:300px}<\/style>\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=Via%20S.%20Giuseppe%201%E2%80%A815020%20Castelletto%20Merli%20%28AL%29&#038;t=m&#038;z=15&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"Via S. Giuseppe 1\u202815020 Castelletto Merli (AL)\"\n\t\t\t\t\taria-label=\"Via S. Giuseppe 1\u202815020 Castelletto Merli (AL)\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0222d85 e-con-full e-flex e-con e-child\" data-id=\"0222d85\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c2a9b90 text-box contactmore icon-default elementor-widget elementor-widget-mae-text-box-grid\" data-id=\"c2a9b90\" data-element_type=\"widget\" data-widget_type=\"mae-text-box-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n\t\t<div class=\"master-text-box-grid grid-container\" data-active=\"1\">\n\t\t\t\t\t\t\t<div class=\"column elementor-repeater-item-1cd8775\">\n\t\t\t\t\t<div class=\"master-text-box\">\n\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tSede operativa\t\t\t\t\t\t<\/h3>\n\t\t\t\t        \n\t\t\t\t        <div class=\"text\">Via S. Giuseppe 4,\u202815020 Castelletto Merli (AL)<\/div>\t\t\t\t    <\/div>\n\t\t\t\t<\/div>\n\t\t    \t\t\t\t<div class=\"column elementor-repeater-item-9139487\">\n\t\t\t\t\t<div class=\"master-text-box\">\n\t\t\t\t\t\t<h3 class=\"title\">\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\tSede legale\t\t\t\t\t\t<\/h3>\n\t\t\t\t        \n\t\t\t\t        <div class=\"text\">Via Lanzone 31, 20123 - Milano (MI)<\/div>\t\t\t\t    <\/div>\n\t\t\t\t<\/div>\n\t\t    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cb59505 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cb59505\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-42d4f1b\" data-id=\"42d4f1b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6737dbd elementor-invisible elementor-widget elementor-widget-mae-headings\" data-id=\"6737dbd\" data-element_type=\"widget\" data-widget_type=\"mae-headings.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"master-heading sep-top\">\n\t\t\t<div class=\"sep\"><\/div>\t        \t        \t<div class=\"pre-heading\">Mettiti in contatto con noi<\/div>\n\t        \n\t        \n\t        \t        <h2 class=\"main-heading\">Scrivici!<\/h2>\n\t        \n\t        \n\t        \t            <div class=\"sub-heading\">Compila il form, riceverai risposta il prima possibile!<\/div>\n\t        \t    <\/div>\n\t    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d758e9e icon-default shake-hover elementor-widget elementor-widget-mae-cta\" data-id=\"d758e9e\" data-element_type=\"widget\" data-widget_type=\"mae-cta.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <a class=\"master-cta\" href=\"tel:0141918004\">\n            <span class=\"image-wrap\"><img fetchpriority=\"high\" decoding=\"async\" width=\"520\" height=\"240\" src=\"https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/image-contact.jpg\" class=\"attachment-full size-full\" alt=\"Image\" srcset=\"https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/image-contact.jpg 520w, https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/image-contact-300x138.jpg 300w\" sizes=\"(max-width: 520px) 100vw, 520px\" \/><\/span>            <span class=\"content-wrap\">\n                <span class=\"icon\"><i aria-hidden=\"true\" class=\"ci-phone-call\"><\/i><\/span>\n                <span class=\"texts\">\n                    <span class=\"text\">0141 918004<\/span>                    <span class=\"phone\">Chiamaci!<\/span>                <\/span>\n            <\/span>\n        <\/a>\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bf90561\" data-id=\"bf90561\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-56cb007 decor-border-top-1 cf7-style-1 elementor-widget elementor-widget-mae-contact-form-7\" data-id=\"56cb007\" data-element_type=\"widget\" data-widget_type=\"mae-contact-form-7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-shortcode ametok-cf7-0\">\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f3720-o1\" lang=\"en-US\" dir=\"ltr\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/index.php\/wp-json\/wp\/v2\/pages\/8003#wpcf7-f3720-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<div style=\"display: none;\">\n<input type=\"hidden\" name=\"_wpcf7\" value=\"3720\" \/>\n<input type=\"hidden\" name=\"_wpcf7_version\" value=\"5.9.3\" \/>\n<input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/>\n<input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f3720-o1\" \/>\n<input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/>\n<input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/div>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nome\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\n<span class=\"input-wrap\"><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-617\"><input size=\"40\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Numero di telefono\" value=\"\" type=\"tel\" name=\"tel-617\" \/><\/span>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"menu-794\"><select class=\"wpcf7-form-control wpcf7-select styled\" aria-invalid=\"false\" name=\"menu-794\"><option value=\"\">Seleziona il servizio<\/option><option value=\"Realizzazione e manutenzione per reti di infrastrutture di servizio urbano\">Realizzazione e manutenzione per reti di infrastrutture di servizio urbano<\/option><option value=\"Trivellazione orizzontale\">Trivellazione orizzontale<\/option><option value=\"Ripristini stradali e asfalti\">Ripristini stradali e asfalti<\/option><option value=\"Scavi e movimento terra\">Scavi e movimento terra<\/option><option value=\"Gestione trasporto e smaltimento di materiali pericolosi\">Gestione trasporto e smaltimento di materiali pericolosi<\/option><option value=\"Demolizioni\">Demolizioni<\/option><\/select><\/span><\/span>\n\n<span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Scrivi qui il tuo messaggio\" name=\"your-message\"><\/textarea><\/span>\n\n<input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Invia\" \/><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-323b155 elementor-section-stretched has-border-top elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"323b155\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db430e2\" data-id=\"db430e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-168ab7f elementor-widget elementor-widget-mae-partner-carousel\" data-id=\"168ab7f\" data-element_type=\"widget\" data-widget_type=\"mae-partner-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n        <div class=\"master-carousel-box\" data-config='{\"column\":\"5\",\"gap\":\"0px\",\"arrowPosition\":null,\"arrowMiddleOffset\":null,\"arrowTopOffset\":null,\"dotOffset\":null,\"stretch\":\"no\",\"autoPlay\":true,\"prevNextButtons\":false,\"pageDots\":false,\"activeIndex\":\"\"}'>\n                            <div class=\"master-partner item-carousel\">\n                    <img decoding=\"async\" width=\"468\" height=\"140\" src=\"https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo.png 468w, https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo-300x90.png 300w\" sizes=\"(max-width: 468px) 100vw, 468px\" \/>                <\/div>\n                            <div class=\"master-partner item-carousel\">\n                    <img decoding=\"async\" width=\"468\" height=\"140\" src=\"https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo.png 468w, https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo-300x90.png 300w\" sizes=\"(max-width: 468px) 100vw, 468px\" \/>                <\/div>\n                            <div class=\"master-partner item-carousel\">\n                    <img decoding=\"async\" width=\"468\" height=\"140\" src=\"https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo.png 468w, https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo-300x90.png 300w\" sizes=\"(max-width: 468px) 100vw, 468px\" \/>                <\/div>\n                            <div class=\"master-partner item-carousel\">\n                    <img decoding=\"async\" width=\"468\" height=\"140\" src=\"https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo.png 468w, https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo-300x90.png 300w\" sizes=\"(max-width: 468px) 100vw, 468px\" \/>                <\/div>\n                            <div class=\"master-partner item-carousel\">\n                    <img decoding=\"async\" width=\"468\" height=\"140\" src=\"https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo.png 468w, https:\/\/edil-cave.it\/wp-content\/uploads\/2021\/08\/partner-logo-300x90.png 300w\" sizes=\"(max-width: 468px) 100vw, 468px\" \/>                <\/div>\n                    <\/div>\n\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ecco come trovarci I nostri contatti Sede operativa Via S. Giuseppe 4,\u202815020 Castelletto Merli (AL) Sede legale Via Lanzone 31, 20123 &#8211; Milano (MI) Mettiti in contatto con noi Scrivici! Compila il form, riceverai risposta il prima possibile! 0141 918004 Chiamaci! Seleziona il servizioRealizzazione e manutenzione per reti di infrastrutture<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8003","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/edil-cave.it\/index.php\/wp-json\/wp\/v2\/pages\/8003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edil-cave.it\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/edil-cave.it\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/edil-cave.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/edil-cave.it\/index.php\/wp-json\/wp\/v2\/comments?post=8003"}],"version-history":[{"count":60,"href":"https:\/\/edil-cave.it\/index.php\/wp-json\/wp\/v2\/pages\/8003\/revisions"}],"predecessor-version":[{"id":9815,"href":"https:\/\/edil-cave.it\/index.php\/wp-json\/wp\/v2\/pages\/8003\/revisions\/9815"}],"wp:attachment":[{"href":"https:\/\/edil-cave.it\/index.php\/wp-json\/wp\/v2\/media?parent=8003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}